{"id":23103,"date":"2024-05-19T17:17:09","date_gmt":"2024-05-19T17:17:09","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/gzorg\/?p=23103"},"modified":"2024-05-19T17:17:09","modified_gmt":"2024-05-19T17:17:09","slug":"leer-no-es-malo-para-la-vista-6-mitos-sobre-la-lectura-y-la-salud-ocular-y-su-explicacion","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/gzorg\/leer-no-es-malo-para-la-vista-6-mitos-sobre-la-lectura-y-la-salud-ocular-y-su-explicacion\/","title":{"rendered":"Leer no es malo para la vista: 6 mitos sobre la lectura y la salud ocular (y su explicaci\u00f3n)"},"content":{"rendered":"<p>Leer no es malo para la vista: 6 mitos sobre la lectura y la salud ocular (y su explicaci\u00f3n)<br \/>\n<a href=\"https:\/\/www.educaciontrespuntocero.com\/noticias\/salud-ocular-leer\/\" class=\"autohyperlink\">www.educaciontrespuntocero.com\/noticias\/salud-ocular-leer\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leer no es malo para la vista: 6 mitos sobre la lectura y la salud ocular (y su explicaci\u00f3n) <a href=\"http:\/\/www.educaciontrespuntocero.com\/noticias\/salud-ocular-leer\/\" class=\"autohyperlink\">www.educaciontrespuntocero.com\/noticias\/salud-ocular-leer\/<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1,49],"tags":[],"class_list":["post-23103","post","type-post","status-publish","format-standard","hentry","category-interessantnieuws","category-oogzorg-interessantnieuws"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:44:43","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/23103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/comments?post=23103"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/23103\/revisions"}],"predecessor-version":[{"id":23104,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/23103\/revisions\/23104"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/media?parent=23103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/categories?post=23103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/tags?post=23103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}