{"id":11958,"date":"2020-05-06T15:24:44","date_gmt":"2020-05-06T15:24:44","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/gzorg\/?p=11958"},"modified":"2020-05-06T15:24:44","modified_gmt":"2020-05-06T15:24:44","slug":"covid-19-le-chu-de-bordeaux-et-simforhealth-creent-un-simulateur-numerique-de-formation-pour-les-soignants","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/gzorg\/covid-19-le-chu-de-bordeaux-et-simforhealth-creent-un-simulateur-numerique-de-formation-pour-les-soignants\/","title":{"rendered":"Covid-19: le CHU de Bordeaux et SimForHealth cr\u00e9ent un simulateur num\u00e9rique de formation pour les soignants"},"content":{"rendered":"<p>Sant\u00e9 Mentale &#8211; Covid-19: le CHU de Bordeaux et SimForHealth cr\u00e9ent un simulateur num\u00e9rique de formation pour les soignants<br \/>\n<a href=\"https:\/\/www.santementale.fr\/actualites\/le-chu-de-bordeaux-et-simforhealth-creent-le-covid-19-le-chu-de-bordeaux-et-simforhealth-creent-un-simulateur-numerique-de-formation-pour-les-soignants.html\" class=\"autohyperlink\">www.santementale.fr\/actualites\/le-chu-de-bordeaux-et-simforhealth-creent-le-covid-19-le-chu-de-bordeaux-et-simforhealth-creent-un-simulateur-numerique-de-formation-pour-les-soignants.html<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sant\u00e9 Mentale &#8211; Covid-19: le CHU de Bordeaux et SimForHealth cr\u00e9ent un simulateur num\u00e9rique de formation pour les soignants www.santementale.fr\/actualites\/le-chu-de-bordeaux-et-simforhealth-creent-le-covid-19-le-chu-de-bordeaux-et-simforhealth-creent-un-simulateur-numerique-de-formation-pour-les-soignants.html<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[39],"tags":[],"class_list":["post-11958","post","type-post","status-publish","format-standard","hentry","category-e-health"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:29:33","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/11958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/comments?post=11958"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/11958\/revisions"}],"predecessor-version":[{"id":11959,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/posts\/11958\/revisions\/11959"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/media?parent=11958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/categories?post=11958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/gzorg\/wp-json\/wp\/v2\/tags?post=11958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}