{"id":9868,"date":"2016-08-09T08:45:38","date_gmt":"2016-08-09T08:45:38","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=9868"},"modified":"2024-01-02T13:48:05","modified_gmt":"2024-01-02T13:48:05","slug":"inspiracion-literatura","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/inspiracion-literatura\/","title":{"rendered":"Inspiraci\u00f3n: literatura"},"content":{"rendered":"<p>Se est\u00e1n terminando las vacaciones, de modo que hay que aprovechar lentamente y con gusto estas semanas para rearmar sus reservas. Puede ser \u00fatil e interesante\u00a0el sitio <strong>Libr\u00f3patas.com<\/strong> <a href=\"http:\/\/www.libropatas.com\/\" class=\"autohyperlink\">www.libropatas.com\/<\/a>, un sitio sobre literatura llevado por entusiastas.<\/p>\n<p><a href=\"http:\/\/hlrnet.com\/sites\/wp-content\/uploads\/2016\/08\/libropatas.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-366 alignnone\" src=\"http:\/\/hlrnet.com\/sites\/wp-content\/uploads\/2016\/08\/libropatas-300x167.png\" alt=\"libropatas\" width=\"300\" height=\"167\" \/><\/a><\/p>\n<p>Sus m\u00e1s recientes publicaciones:<\/p>\n<p>[rssinpage rssfeed=&#8217;http:\/\/www.libropatas.com\/feed\/&#8217;]<\/p>\n<p>Si tienes ganas de ver m\u00e1s: el sitio <strong>Libr\u00fajula.com<\/strong> (<a href=\"http:\/\/www.librujula.com\" class=\"autohyperlink\">www.librujula.com<\/a>) tambi\u00e9n merece una visita<\/p>\n<p>[rssinpage rssfeed=&#8217;http:\/\/librujula.com\/?format=feed&amp;type=rss&#8217;]<\/p>\n<p>tanto como <strong><a href=\"http:\/\/Librotea.com\" class=\"autohyperlink\">Librotea.com<\/a><\/strong>, un sitio de El Pa\u00eda (<a href=\"http:\/\/librotea.com\/explorar\" class=\"autohyperlink\">librotea.com\/explorar<\/a>). que desgraciadamente no tiene hilo RSS. Este \u00faltimo sitio requiere login, que se puede hacer con la cuenta de Facebook.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se est\u00e1n terminando las vacaciones, de modo que hay que aprovechar lentamente y con gusto estas semanas para rearmar sus reservas. Puede ser \u00fatil e interesante\u00a0el sitio Libr\u00f3patas.com <a href=\"http:\/\/www.libropatas.com\/,\" class=\"autohyperlink\">www.libropatas.com\/,<\/a> un sitio sobre literatura llevado por entusiastas. Sus m\u00e1s recientes publicaciones: [rssinpage rssfeed=&#8217;<a href=\"http:\/\/www.libropatas.com\/feed\/&#8217;%5D\" class=\"autohyperlink\">www.libropatas.com\/feed\/&#8217;%5D<\/a> Si tienes ganas de ver m\u00e1s: el sitio<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12,107],"tags":[98,202],"class_list":["post-9868","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes","category-lecturas","tag-literatura","tag-noticias-y-enlaces"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:40:52","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/9868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=9868"}],"version-history":[{"count":5,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/9868\/revisions"}],"predecessor-version":[{"id":9878,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/9868\/revisions\/9878"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=9868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=9868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=9868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}