{"id":6951,"date":"2014-09-27T06:48:54","date_gmt":"2014-09-27T06:48:54","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=6951"},"modified":"2018-01-15T09:21:11","modified_gmt":"2018-01-15T09:21:11","slug":"herramientas-tic-y-ele-algunas-pautas","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/herramientas-tic-y-ele-algunas-pautas\/","title":{"rendered":"Herramientas TIC y ELE: algunas pautas"},"content":{"rendered":"<p>Presentaci\u00f3n de mi session en la Jornada del 27 de septiembre en Odisee<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/onedrive.live.com\/embed?cid=81AF80ABA6FF6326&amp;resid=81AF80ABA6FF6326%2152357&amp;authkey=AHLy1SHz2ddOi4Y&amp;em=2&amp;wdAr=1.7769911504424778\" width=\"610px\" height=\"367px\" frameborder=\"0\">Dit is een ingesloten <a target=\"_blank\" href=\"http:\/\/office.com\">Microsoft Office<\/a>-presentatiebestand dat mogelijk is gemaakt door <a target=\"_blank\" href=\"http:\/\/office.com\/webapps\">Office Online<\/a>.<\/iframe><br \/>\nApuntes de clase: <a href=\"http:\/\/hlrnet.com\/sites\/alt164\/files\/2014\/09\/2709.txt\">2709<\/a><br \/>\nFichas interesantes<\/p>\n<ul>\n<li><span class=\"matXL\"><a href=\"http:\/\/office.microsoft.com\/es-es\/support\/beknopte-handleiding-voor-word-2013-HA103673715.aspx\">Gu\u00eda de inicio r\u00e1pido de Word 2013<\/a><\/span><\/li>\n<li><span class=\"matXL\"><a href=\"http:\/\/office.microsoft.com\/es-es\/word-help\/nieuw-in-word-2013-HA102809597.aspx\">Novedades de Word 2013<\/a><\/span><\/li>\n<li><a href=\"http:\/\/office.microsoft.com\/es-es\/word-help\/wijzigingen-bijhouden-HA102840151.aspx?CTT=1\">Control de cambios<\/a><\/li>\n<li><a href=\"http:\/\/office.microsoft.com\/es-es\/word-help\/remove-tracked-changes-and-comments-from-a-document-HA101822263.aspx\">Quitar las marcas de revisi\u00f3n y los comentarios de un documento<\/a><\/li>\n<li><a href=\"http:\/\/windows.microsoft.com\/es-es\/onedrive\/windows-app-faq\">Aplicaci\u00f3n de escritorio OneDrive para Windows: preguntas m\u00e1s frecuentes<\/a><\/li>\n<li><a href=\"http:\/\/office.microsoft.com\/es-es\/outlook-help\/inleiding-tot-rss-HA001230463.aspx\">Introducci\u00f3n a RSS<\/a><\/li>\n<li>Leer fuentes RSS<\/li>\n<li><a href=\"http:\/\/windows.microsoft.com\/es-es\/onedrive\/onedrive-help#onedrive=other\">OneDrive<\/a><\/li>\n<li><a href=\"http:\/\/office.microsoft.com\/es-es\/outlook-help\/een-abonnement-op-een-rss-kanaal-nemen-HA010355679.aspx\">Suscripci\u00f3n a una fuente RSS<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Presentaci\u00f3n de mi session en la Jornada del 27 de septiembre en Odisee Dit is een ingesloten Microsoft Office-presentatiebestand dat mogelijk is gemaakt door Office Online. Apuntes de clase: 2709 Fichas interesantes Gu\u00eda de inicio r\u00e1pido de Word 2013 Novedades de Word 2013 Control de cambios Quitar las marcas de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[13],"tags":[101],"class_list":["post-6951","post","type-post","status-publish","format-standard","hentry","category-materiales","tag-tic"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:44:28","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=6951"}],"version-history":[{"count":5,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6951\/revisions"}],"predecessor-version":[{"id":11354,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6951\/revisions\/11354"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=6951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=6951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=6951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}