{"id":6617,"date":"2014-06-14T13:02:21","date_gmt":"2014-06-14T13:02:21","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=6617"},"modified":"2014-06-14T13:02:21","modified_gmt":"2014-06-14T13:02:21","slug":"bv-h","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/bv-h\/","title":{"rendered":"b\/v &#8211; h"},"content":{"rendered":"<p>Si te duelen la B y la V, o la H, o si hacen da\u00f1o a tus almunos, puede ser \u00fatil ver la <a href=\"http:\/\/reglasdeortografia.com\/homofonas.html\">lista de hom\u00f3fonas<\/a> de <a href=\"http:\/\/reglasdeortografia.com\">Reglas de Ortograf\u00eda<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si te duelen la B y la V, o la H, o si hacen da\u00f1o a tus almunos, puede ser \u00fatil ver la lista de hom\u00f3fonas de Reglas de Ortograf\u00eda.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12,32,13],"tags":[],"class_list":["post-6617","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes","category-herramientas","category-materiales"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:32:24","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=6617"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6617\/revisions"}],"predecessor-version":[{"id":6618,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/6617\/revisions\/6618"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=6617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=6617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=6617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}