{"id":611,"date":"2011-06-12T11:12:01","date_gmt":"2011-06-12T11:12:01","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=611"},"modified":"2023-05-17T13:41:49","modified_gmt":"2023-05-17T13:41:49","slug":"ideas-afines","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/ideas-afines\/","title":{"rendered":"Ideas afines"},"content":{"rendered":"<p>Ideas afines fue a su \u00e9poca un sitio argentino que, a partir de la palabra buscada por el usuario, propone una lista de otras palabras contiguas.<\/p>\n<p>Justifica su subt\u00edtulo \u00abGenerador de ideas\u00bb en que esta lista puede contener (y proponer a un@ escritor@) palabras que en cierto contexto o por cierto matiz convienen mejor en una ocasi\u00f3n dada.<\/p>\n<p>Hay m\u00e1s herramientas que se pueden usar para buscar palabras afines:<\/p>\n<ul>\n<li>DiCE: Diccionario de Colocaciones del Espa\u00f1ol: Paginas<br \/>\n<a href=\"http:\/\/www.dicesp.com\/paginas\" class=\"autohyperlink\">www.dicesp.com\/paginas<\/a><\/li>\n<li>Diccionario Inspirassion<br \/>\n<a href=\"https:\/\/inspirassion.com\/es\/\" class=\"autohyperlink\">inspirassion.com\/es\/<\/a><\/li>\n<li>Goodrae &#8211; Diccionario de la RAE hipertextual, lematizado e inverso.<br \/>\n<a href=\"http:\/\/recursosdidacticos.es\/goodrae\/index.php\" class=\"autohyperlink\">recursosdidacticos.es\/goodrae\/index.php<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ideas afines fue a su \u00e9poca un sitio argentino que, a partir de la palabra buscada por el usuario, propone una lista de otras palabras contiguas. Justifica su subt\u00edtulo \u00abGenerador de ideas\u00bb en que esta lista puede contener (y proponer a un@ escritor@) palabras que en cierto contexto o por<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":13,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12],"tags":[155,100,101],"class_list":["post-611","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes","tag-diccionario","tag-lengua","tag-tic"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:50:29","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":5,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"predecessor-version":[{"id":22363,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/611\/revisions\/22363"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}