{"id":593,"date":"2009-02-12T11:06:22","date_gmt":"2009-02-12T11:06:22","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=593"},"modified":"2016-08-06T21:15:59","modified_gmt":"2016-08-06T21:15:59","slug":"usuarioscomoyo","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/usuarioscomoyo\/","title":{"rendered":"Usuarioscomoyo"},"content":{"rendered":"<p>La web Usuari@sComoyo (<a href=\"http:\/\/www.usuarioscomoyo.com\" class=\"autohyperlink\">www.usuarioscomoyo.com<\/a> ) que se acaba de estrenar es una iniciativa del Ayuntamiento de Madrid y de las asociaciones de internautas y usuarios que se destina a usuarios, y que propone una plataforma en la que se puede proponer dudas y encontrar soluciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La web Usuari@sComoyo (<a href=\"http:\/\/www.usuarioscomoyo.com\" class=\"autohyperlink\">www.usuarioscomoyo.com<\/a> ) que se acaba de estrenar es una iniciativa del Ayuntamiento de Madrid y de las asociaciones de internautas y usuarios que se destina a usuarios, y que propone una plataforma en la que se puede proponer dudas y encontrar soluciones.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12],"tags":[],"class_list":["post-593","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:39:01","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"predecessor-version":[{"id":9867,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/593\/revisions\/9867"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}