{"id":481,"date":"2005-03-12T10:14:51","date_gmt":"2005-03-12T10:14:51","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=481"},"modified":"2013-02-10T19:23:50","modified_gmt":"2013-02-10T19:23:50","slug":"hay-tormenta","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/hay-tormenta\/","title":{"rendered":"Hay tormenta"},"content":{"rendered":"<p><strong>Hay tormenta<\/strong><br \/>\nEn el manual usado (Prisma, Edinumen) se dice que se se puede decir \u00abHay tormenta\u00bb como \u00abHace tormenta\u00bb. Deseando clarificar las cosas, veo que:<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"80\">hay tormenta<\/td>\n<td align=\"right\" width=\"64\">2710<\/td>\n<td align=\"right\" width=\"64\">72,85%<\/td>\n<\/tr>\n<tr>\n<td>hay una tormenta<\/td>\n<td align=\"right\">898<\/td>\n<td align=\"right\">24,14%<\/td>\n<\/tr>\n<tr>\n<td>hace tormenta<\/td>\n<td align=\"right\">51<\/td>\n<td align=\"right\">1,37%<\/td>\n<\/tr>\n<tr>\n<td>hace una tormenta<\/td>\n<td align=\"right\">61<\/td>\n<td align=\"right\">1,64%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>(Google 05.03.2005)<br \/>\nO une predominaci\u00f3n s\u00f3lida e incontestable de la forma HAY, y la predominaci\u00f3n es a\u00fan m\u00e1s fuerte si hay art\u00edculo. \u00bfSe podr\u00eda tratar de un caso particular?<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"80\">hay viento<\/td>\n<td align=\"right\" width=\"64\">9890<\/td>\n<td align=\"right\" width=\"64\">73,59%<\/td>\n<\/tr>\n<tr>\n<td>hace viento<\/td>\n<td align=\"right\">3550<\/td>\n<td align=\"right\">26,41%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>(Google 05.03.2005)<br \/>\nNo, aqu\u00ed tambi\u00e9n la forma HAY es m\u00e1s frecuente. Aconsejar\u00e9 luego HAY en expresiones con sustantivo (a la excepci\u00f3n de <em>hace calor<\/em>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay tormenta En el manual usado (Prisma, Edinumen) se dice que se se puede decir \u00abHay tormenta\u00bb como \u00abHace tormenta\u00bb. Deseando clarificar las cosas, veo que: hay tormenta 2710 72,85% hay una tormenta 898 24,14% hace tormenta 51 1,37% hace una tormenta 61 1,64% (Google 05.03.2005) O une predominaci\u00f3n s\u00f3lida<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[22],"tags":[],"class_list":["post-481","post","type-post","status-publish","format-standard","hentry","category-dudas"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:31:27","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=481"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/481\/revisions"}],"predecessor-version":[{"id":3596,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/481\/revisions\/3596"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}