{"id":26876,"date":"2025-09-20T14:58:53","date_gmt":"2025-09-20T14:58:53","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=26876"},"modified":"2025-09-20T14:58:53","modified_gmt":"2025-09-20T14:58:53","slug":"noticias-positivas-del-20-9-25","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/noticias-positivas-del-20-9-25\/","title":{"rendered":"Noticias positivas del 20\/9\/25"},"content":{"rendered":"<p>La esponja vegetal que aspira a limpiar el mundo de micropl\u00e1sticos crece en Galicia | Noticias de Galicia | EL PA\u00cdS<br \/>\nUn ingeniero forestal decidi\u00f3 apostarlo todo hace 15 a\u00f1os al cultivo de luffa, una cucurbit\u00e1cea que descubri\u00f3 en Paraguay. Hoy es el mayor exportador de este material cosm\u00e9tico en Europa<br \/>\n<a href=\"https:\/\/elpais.com\/espana\/galicia\/2025-02-16\/la-esponja-vegetal-que-aspira-a-limpiar-el-mundo-de-microplasticos-crece-en-galicia.html\" class=\"autohyperlink\">elpais.com\/espana\/galicia\/2025-02-16\/la-esponja-vegetal-que-aspira-a-limpiar-el-mundo-de-microplasticos-crece-en-galicia.html<\/a><\/p>\n<p>El hielo como generador el\u00e9ctrico: el descubrimiento que cambia c\u00f3mo entendemos las tormentas<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/09\/18\/el-hielo-como-generador-electrico-el-descubrimiento-que-cambia-como-entendemos-las-tormentas\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/09\/18\/el-hielo-como-generador-electrico-el-descubrimiento-que-cambia-como-entendemos-las-tormentas\/<\/a><\/p>\n<p>Los cient\u00edficos han doblado hielo salado y han descubierto que se comporta como un generador el\u00e9ctrico<br \/>\nLa investigaci\u00f3n muestra que el hielo salado puede alcanzar valores comparables a los mejores materiales piezoel\u00e9ctricos. El efecto nace de un detalle microsc\u00f3pico: el agua salada que queda atrapada entre los cristales de hielo<br \/>\n<a href=\"https:\/\/www.xataka.com\/energia\/cientificos-han-doblado-hielo-salado-han-descubierto-que-se-comporta-como-generador-electrico\" class=\"autohyperlink\">www.xataka.com\/energia\/cientificos-han-doblado-hielo-salado-han-descubierto-que-se-comporta-como-generador-electrico<\/a><\/p>\n<p>Vender humo ahora es un negocio en Soria: lo purifica y lo vende como CO2 para hacer refrescos<br \/>\nUn proyecto de 8,9 millones conecta una central de biomasa con una planta de captura y purificaci\u00f3n de di\u00f3xido de carbono. Mientras Noruega entierra su CO\u2082 bajo el mar, Castilla y Le\u00f3n lo convierte en un producto comercial<br \/>\n<a href=\"https:\/\/www.xataka.com\/energia\/vender-humo-ahora-negocio-soria-purifica-vende-como-co2-para-hacer-refrescos\" class=\"autohyperlink\">www.xataka.com\/energia\/vender-humo-ahora-negocio-soria-purifica-vende-como-co2-para-hacer-refrescos<\/a><\/p>\n<p>Los posos del caf\u00e9 son un residuo muy problem\u00e1tico, pero hay una soluci\u00f3n para que no acaben en el vertedero: convertirlos en hormig\u00f3n. Adem\u00e1s de aprovechar un material org\u00e1nico que genera toneladas de basura, podr\u00eda ayudar a mitigar otro problema con gran impacto medioambiental<br \/>\n<a href=\"https:\/\/www.directoalpaladar.com\/consumidores\/posos-cafe-residuo-muy-problematico-hay-solucion-no-acaben-vertedero-convertirlos-hormigon\" class=\"autohyperlink\">www.directoalpaladar.com\/consumidores\/posos-cafe-residuo-muy-problematico-hay-solucion-no-acaben-vertedero-convertirlos-hormigon<\/a><\/p>\n<p>Y ADEMAS INTERESANTE (O POR LO MENOS IMPORTANTE)<\/p>\n<p>El boom de la comida preparada en los supermercados tiene un punto ciego: la nutrici\u00f3n. \u00bfEstamos poniendo a los zorros a cuidar del gallinero? El boom de los productos ultraprocesados afecto seriamente a la dieta. \u00bfTendr\u00e1 un efecto parecido esta tendencia?<br \/>\n<a href=\"https:\/\/www.xataka.com\/medicina-y-salud\/cruzada-supermercados-cocina-casera-esta-funcionando-pregunta-nutricional-estamos-poniendo-a-zorros-a-cuidar-gallinero\" class=\"autohyperlink\">www.xataka.com\/medicina-y-salud\/cruzada-supermercados-cocina-casera-esta-funcionando-pregunta-nutricional-estamos-poniendo-a-zorros-a-cuidar-gallinero<\/a><\/p>\n<p>Un casete de ADN capaz de almacenar todos los archivos digitales del mundo<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/09\/18\/un-casete-de-adn-capaz-de-almacenar-todos-los-archivos-digitales-del-mundo\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/09\/18\/un-casete-de-adn-capaz-de-almacenar-todos-los-archivos-digitales-del-mundo\/<\/a><\/p>\n<p>En 2007 Machu Picchu se convirti\u00f3 en una de las &#8216;Siete Maravillas del Mundo&#8217;. Ahora es v\u00edctima de su enorme \u00e9xito tur\u00edstico<br \/>\nEl famoso yacimiento inca se arriesga a perder su hueco en la lista de las Nuevas Maravillas del Mundo. El Gobierno calcula que este a\u00f1o la zona recibir\u00e1 m\u00e1s de 1,5 millones de turistas, \u00abuna cifra hist\u00f3rica\u00bb<br \/>\n<a href=\"https:\/\/www.xataka.com\/magnet\/machu-picchu-se-ha-convertido-tal-feria-turistica-que-ahora-corre-riesgo-mayor-perder-estatus-maravilla-mundo\" class=\"autohyperlink\">www.xataka.com\/magnet\/machu-picchu-se-ha-convertido-tal-feria-turistica-que-ahora-corre-riesgo-mayor-perder-estatus-maravilla-mundo<\/a><\/p>\n<p>Antes los turistas visitaban Espa\u00f1a en busca de sol, playa y comida. Ahora a\u00f1aden algo m\u00e1s a la lista: bodorrios<br \/>\nLas \u00abdestination weddings\u00bb se popularizan y son ya un pilar para algunas fincas de Mallorca. \u00abHay mucho americano, mucho alem\u00e1n, mucho brit\u00e1nico. Aqu\u00ed se lo ponemos todo muy f\u00e1cil\u00bb<br \/>\n<a href=\"https:\/\/www.xataka.com\/magnet\/antes-turistas-visitaban-espana-busca-sol-playa-comida-ahora-anaden-algo-a-lista-casarse\" class=\"autohyperlink\">www.xataka.com\/magnet\/antes-turistas-visitaban-espana-busca-sol-playa-comida-ahora-anaden-algo-a-lista-casarse<\/a><\/p>\n<p>Meta va tan en serio con las gafas inteligentes que su cat\u00e1logo ya es un l\u00edo: as\u00ed se diferencian los nuevos modelos<br \/>\n<a href=\"https:\/\/www.xataka.com\/wearables\/meta-va-serio-gafas-inteligentes-que-su-catalogo-lio-asi-se-diferencian-nuevos-modelos\" class=\"autohyperlink\">www.xataka.com\/wearables\/meta-va-serio-gafas-inteligentes-que-su-catalogo-lio-asi-se-diferencian-nuevos-modelos<\/a><\/p>\n<p>Google acaba de integrar su IA en Chrome. Es el principio del fin del navegador tradicional<br \/>\n<a href=\"https:\/\/www.xataka.com\/robotica-e-ia\/google-acaba-integrar-su-ia-chrome-principio-fin-navegador-tradicional\" class=\"autohyperlink\">www.xataka.com\/robotica-e-ia\/google-acaba-integrar-su-ia-chrome-principio-fin-navegador-tradicional<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La esponja vegetal que aspira a limpiar el mundo de micropl\u00e1sticos crece en Galicia | Noticias de Galicia | EL PA\u00cdS Un ingeniero forestal decidi\u00f3 apostarlo todo hace 15 a\u00f1os al cultivo de luffa, una cucurbit\u00e1cea que descubri\u00f3 en Paraguay. Hoy es el mayor exportador de este material cosm\u00e9tico en<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[175],"tags":[197],"class_list":["post-26876","post","type-post","status-publish","format-standard","hentry","category-noticias-positivas","tag-noticias-positivas"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:33:48","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=26876"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26876\/revisions"}],"predecessor-version":[{"id":26877,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26876\/revisions\/26877"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=26876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=26876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=26876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}