{"id":26705,"date":"2025-07-24T11:14:08","date_gmt":"2025-07-24T11:14:08","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=26705"},"modified":"2025-07-24T11:14:08","modified_gmt":"2025-07-24T11:14:08","slug":"noticias-interesantes-del-24-7-25","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/noticias-interesantes-del-24-7-25\/","title":{"rendered":"Noticias interesantes del 24\/7\/25"},"content":{"rendered":"<p>NOTICIAS POSITIVAS<\/p>\n<p>La nueva era de los electrodom\u00e9sticos: cuando el hogar empieza a saldar su deuda con el planeta<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/07\/17\/la-nueva-era-de-los-electrodomesticos-cuando-el-hogar-empieza-a-saldar-su-deuda-con-el-planeta\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/17\/la-nueva-era-de-los-electrodomesticos-cuando-el-hogar-empieza-a-saldar-su-deuda-con-el-planeta\/<\/a><\/p>\n<p>Y ADEMAS INTERESANTE (O POR LO MENOS IMPORTANTE)<\/p>\n<p>El 22 de julio de 2025 no ha sido un d\u00eda normal. Ha sido uno de los d\u00edas m\u00e1s cortos en toda la historia de la Tierra<br \/>\nSe espera que este 22 de julio el planeta complete su rotaci\u00f3n 1,34 milisegundos antes de las 24 horas. La Tierra deber\u00eda estar ralentiz\u00e1ndose, pero se est\u00e1 acelerando, y hoy es uno de sus d\u00edas m\u00e1s r\u00e1pidos<br \/>\n<a href=\"https:\/\/www.xataka.com\/espacio\/hoy-tierra-gira-rapido-normal-estamos-atravesando-uno-dias-cortos-toda-historia\" class=\"autohyperlink\">www.xataka.com\/espacio\/hoy-tierra-gira-rapido-normal-estamos-atravesando-uno-dias-cortos-toda-historia<\/a><\/p>\n<p>El efecto mariposa: una decisi\u00f3n de Netscape en los 90 explica por qu\u00e9 Google y Meta crecen con cada revoluci\u00f3n tecnol\u00f3gica<br \/>\nUna decisi\u00f3n t\u00e9cnica de seguridad de 1995 cre\u00f3 sin querer los monopolios digitales actuales y puede ser decisiva en la era de la IA<br \/>\n<a href=\"https:\/\/www.xataka.com\/seguridad\/efecto-mariposa-decision-netscape-90-explica-que-google-meta-crecen-cada-revolucion-tecnologica\" class=\"autohyperlink\">www.xataka.com\/seguridad\/efecto-mariposa-decision-netscape-90-explica-que-google-meta-crecen-cada-revolucion-tecnologica<\/a><\/p>\n<p>El lenguaje secreto de las plantas: c\u00f3mo \u201chablan\u201d sin palabras<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/07\/22\/el-lenguaje-secreto-de-las-plantas-como-hablan-sin-palabras\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/22\/el-lenguaje-secreto-de-las-plantas-como-hablan-sin-palabras\/<\/a><\/p>\n<p>Los preparacionistas ya no se limitan a almacenar comida enlatada. Ahora guardan IA en un pendrive para el Apocalipsis<br \/>\n<a href=\"https:\/\/www.xataka.com\/robotica-e-ia\/hay-gente-preparandose-para-apocalipsis-ahora-hay-quien-anade-pendrive-ia-a-su-kit-supervivencia\" class=\"autohyperlink\">www.xataka.com\/robotica-e-ia\/hay-gente-preparandose-para-apocalipsis-ahora-hay-quien-anade-pendrive-ia-a-su-kit-supervivencia<\/a><\/p>\n<p>Adi\u00f3s, tomates de Marruecos: la UE tiene un nuevo plan para sus comedores escolares y pasa por verduras \u00abMade in Europe\u00bb<br \/>\n<a href=\"https:\/\/www.xataka.com\/magnet\/nueva-estrategia-agricola-ue-empieza-lugar-inesperado-comedor-escolar\" class=\"autohyperlink\">www.xataka.com\/magnet\/nueva-estrategia-agricola-ue-empieza-lugar-inesperado-comedor-escolar<\/a><\/p>\n<p>Hace cuatro a\u00f1os alguien atropell\u00f3 a un perro en Brasil: hoy sabemos que ni era un perro ni deber\u00eda haber existido<br \/>\nDogxim no fue simplemente una curiosidad gen\u00e9tica, fue un recordatorio de los l\u00edmites difusos entre especies en un mundo cada vez m\u00e1s alterado<br \/>\n<a href=\"https:\/\/www.xataka.com\/ecologia-y-naturaleza\/alguien-atropello-a-perro-analisis-posteriores-revelaron-que-criatura-era-perro-deberia-haber-existido\" class=\"autohyperlink\">www.xataka.com\/ecologia-y-naturaleza\/alguien-atropello-a-perro-analisis-posteriores-revelaron-que-criatura-era-perro-deberia-haber-existido<\/a><\/p>\n<p>El hombre que gan\u00f3 la loter\u00eda 16 veces sin hacer trampas. Su truco eran tan sencillo que lo acabaron prohibiendo<br \/>\n<a href=\"https:\/\/www.xataka.com\/magnet\/probable-que-te-alcance-rayo-a-que-te-toque-loteria-que-economista-rompio-juego-ganando-14-veces\" class=\"autohyperlink\">www.xataka.com\/magnet\/probable-que-te-alcance-rayo-a-que-te-toque-loteria-que-economista-rompio-juego-ganando-14-veces<\/a><\/p>\n<p>Cualquier persona podr\u00eda ense\u00f1ar a un robot: MIT presenta un sistema de entrenamiento sin necesidad de programaci\u00f3n<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/07\/19\/cualquier-persona-podria-ensenar-a-un-robot-mit-presenta-un-sistema-de-entrenamiento-sin-necesidad-de-programacion\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/19\/cualquier-persona-podria-ensenar-a-un-robot-mit-presenta-un-sistema-de-entrenamiento-sin-necesidad-de-programacion\/<\/a><\/p>\n<p>\u00bfPuede la arquitectura curar? C\u00f3mo el dise\u00f1o de los hospitales influye en la recuperaci\u00f3n de los pacientes<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/07\/18\/puede-la-arquitectura-curar-como-el-diseno-de-los-hospitales-influye-en-la-recuperacion-de-los-pacientes\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/18\/puede-la-arquitectura-curar-como-el-diseno-de-los-hospitales-influye-en-la-recuperacion-de-los-pacientes\/<\/a><\/p>\n<p>Airbus y la br\u00fajula cu\u00e1ntica que desaf\u00eda al GPS | WIRED<br \/>\nAirbus, en colaboraci\u00f3n con SandboxAQ, una empresa derivada de Google, ha completado con \u00e9xito 150 horas de vuelo de prueba con MagNav, un revolucionario dispositivo que promete cambiar el paradigma de la ubicaci\u00f3n de aeronaves. Este sistema no depende del GPS, sino que utiliza el campo magn\u00e9tico de la Tierra para orientarse, abriendo una nueva era de resiliencia y seguridad en la aviaci\u00f3n.<br \/>\n<a href=\"https:\/\/es.wired.com\/articulos\/airbus-y-la-brujula-cuantica-que-desafia-al-gps\" class=\"autohyperlink\">es.wired.com\/articulos\/airbus-y-la-brujula-cuantica-que-desafia-al-gps<\/a><\/p>\n<p>Estas misteriosas huellas sugieren que la vida compleja surgi\u00f3 mucho antes de lo que pens\u00e1bamos | WIRED<br \/>\n<a href=\"https:\/\/es.wired.com\/articulos\/estas-misteriosas-huellas-sugieren-que-la-vida-compleja-surgio-mucho-antes-de-lo-que-pensabamos\" class=\"autohyperlink\">es.wired.com\/articulos\/estas-misteriosas-huellas-sugieren-que-la-vida-compleja-surgio-mucho-antes-de-lo-que-pensabamos<\/a><\/p>\n<p>Si la pregunta es c\u00f3mo hacer que un equipo sea m\u00e1s productivo, la respuesta seg\u00fan Jeff Bezos es clara: con dos pizzas<br \/>\n<a href=\"https:\/\/www.xataka.com\/empresas-y-economia\/pregunta-como-hacer-que-equipo-sea-productivo-respuesta-jeff-bezos-clara-dos-pizzas-1\" class=\"autohyperlink\">www.xataka.com\/empresas-y-economia\/pregunta-como-hacer-que-equipo-sea-productivo-respuesta-jeff-bezos-clara-dos-pizzas-1<\/a><\/p>\n<p>Robots que se reparan solos: el nuevo metabolismo artificial que transforma la autonom\u00eda mec\u00e1nica<br \/>\n<a href=\"https:\/\/wwwhatsnew.com\/2025\/07\/17\/robots-que-se-reparan-solos-el-nuevo-metabolismo-artificial-que-transforma-la-autonomia-mecanica\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/17\/robots-que-se-reparan-solos-el-nuevo-metabolismo-artificial-que-transforma-la-autonomia-mecanica\/<\/a><\/p>\n<p>Un meteorito cay\u00f3 en el Sahara en 2023. Ha resultado ser el trozo de Luna que nos faltaba para resolver un viejo enigma<br \/>\nLas muestras de Luna que ten\u00edamos hasta ahora nos dejaban un enorme hueco de casi mil millones de a\u00f1os de historia lunar en los que no sab\u00edamos qu\u00e9 hab\u00eda pasado<br \/>\n<a href=\"https:\/\/www.xataka.com\/espacio\/meteorito-que-cayo-luna-ha-ayudado-a-resolver-misterio-que-misiones-apolo-dejaron-abierto-que-paso-volcanes-lunares\" class=\"autohyperlink\">www.xataka.com\/espacio\/meteorito-que-cayo-luna-ha-ayudado-a-resolver-misterio-que-misiones-apolo-dejaron-abierto-que-paso-volcanes-lunares<\/a><\/p>\n<p>Un joven japon\u00e9s ha tenido la madre de todas las ideas para librarse del trabajo: inventarse su propia religi\u00f3n<br \/>\n    En Jap\u00f3n, la sobrecarga laboral ha llevado a casos extremos de agotamiento<br \/>\n    Para evitarlo, un joven ha creado una religi\u00f3n que proh\u00edbe trabajar horas extra y obliga a sus feligreses a salir a su hora del trabajo<br \/>\n<a href=\"https:\/\/www.xataka.com\/magnet\/japon-joven-ha-ideado-mejor-forma-para-salir-a-su-hora-trabajo-no-hacer-horas-extra-fundar-su-propia-religion\" class=\"autohyperlink\">www.xataka.com\/magnet\/japon-joven-ha-ideado-mejor-forma-para-salir-a-su-hora-trabajo-no-hacer-horas-extra-fundar-su-propia-religion<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOTICIAS POSITIVAS La nueva era de los electrodom\u00e9sticos: cuando el hogar empieza a saldar su deuda con el planeta <a href=\"http:\/\/wwwhatsnew.com\/2025\/07\/17\/la-nueva-era-de-los-electrodomesticos-cuando-el-hogar-empieza-a-saldar-su-deuda-con-el-planeta\/\" class=\"autohyperlink\">wwwhatsnew.com\/2025\/07\/17\/la-nueva-era-de-los-electrodomesticos-cuando-el-hogar-empieza-a-saldar-su-deuda-con-el-planeta\/<\/a> Y ADEMAS INTERESANTE (O POR LO MENOS IMPORTANTE) El 22 de julio de 2025 no ha sido un d\u00eda normal. Ha sido uno de los d\u00edas m\u00e1s cortos en toda<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":11,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[175],"tags":[],"class_list":["post-26705","post","type-post","status-publish","format-standard","hentry","category-noticias-positivas"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 19:56:48","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=26705"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26705\/revisions"}],"predecessor-version":[{"id":26706,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/26705\/revisions\/26706"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=26705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=26705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=26705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}