{"id":25834,"date":"2024-11-30T12:17:54","date_gmt":"2024-11-30T12:17:54","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=25834"},"modified":"2024-11-30T12:28:51","modified_gmt":"2024-11-30T12:28:51","slug":"practicando-del-imperfecto-de-subjuntivo","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/practicando-del-imperfecto-de-subjuntivo\/","title":{"rendered":"Practicando del imperfecto de subjuntivo"},"content":{"rendered":"<p>Os presento una serie de actividades que organic\u00e9 cuando los alumnos de final de B1 me se\u00f1alaron que les costaba el imperfecto de subjuntivo.<\/p>\n<p>1 &#8211; Repaso de la formaci\u00f3n<\/p>\n<p>Si tu manual no lo tiene, podr\u00e1s encontrar un esquema en l\u00ednea.<\/p>\n<p>2a &#8211; Los ejercicios de formaci\u00f3n (lo que suelo llamar &#8216;gimnasia de las formas&#8217;) los prefiero hacer en l\u00ednea desde el ordenador que manejo en el aula &#8211; la correcci\u00f3n est\u00e1 integrada, y puede que les anime a practicar en casa.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.espagnolfacile.com\/exercices\/exercice-espagnol-2\/exercice-espagnol-28262.php\">www.espagnolfacile.com\/exercices\/exercice-espagnol-2\/exercice-espagnol-28262.php<\/a><\/li>\n<\/ul>\n<p>2b &#8211; Un juego de formas, como una la cadena de condiciones<\/p>\n<p><em>Si pudiera, \u2026.<\/em> (y el pr\u00f3ximo alumno retoma el verbo que acaba de usar el previo)<\/p>\n<p>3 &#8211; Un v\u00eddeo que puede dar de hablar, como este reel sobre la evoluci\u00f3n de caminar en pareja<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/reel\/1472000716846142\">www.facebook.com\/reel\/1472000716846142<\/a><\/p>\n<p><a href=\"https:\/\/espanol.lingolia.com\/es\/gramatica\/tiempos-subjuntivo\/preterito-imperfecto\/ejercicios\" class=\"autohyperlink\">espanol.lingolia.com\/es\/gramatica\/tiempos-subjuntivo\/preterito-imperfecto\/ejercicios<\/a><\/p>\n<p>Comentar el v\u00eddeo a partir de las estructuras (No) era normal que&#8230; \/ No me parece aceptable que &#8230;<\/p>\n<p>[o en un primer moment se puede hacer en presente &#8211; <em>(No) es normal que&#8230;<\/em>]<\/p>\n<p>4- conversaci\u00f3n \/ escritura: quejas a un proveedor &#8211; por ejemplo de internet, tel\u00e9fono, electricidad, gas, agua<\/p>\n<p><em>Es injusto que un funcione, que sea tan caro, que vuestros servicios no incluyan \u2026., que tenga que esperar tanto<\/em><\/p>\n<p><em>Hubiera preferido que \u2026 vuestros servicios incluyeran\u2026, fueran menos caros<\/em><\/p>\n<p>5 &#8211; Un v\u00eddeo que da de hablar [o sino a partir de un tema como el transporte, la medicina, la cultura, las relaciones sociales, la comida, los estudios, el trabajo, &#8230;]<\/p>\n<p>Un maestro en 1985 &#8211; <a href=\"https:\/\/www.facebook.com\/reel\/943887627599682\">www.facebook.com\/reel\/943887627599682<\/a><\/p>\n<p><em>Antes se esperaba que \/ era normal que \/ era imperativo que<\/em><\/p>\n<p><em>Ahora es normal que<\/em><\/p>\n<p>6 &#8211; La consultor\u00eda: imaginad el problema, y las soluciones propuestas<\/p>\n<p>(a partir de la foto de una pareja en una consultor\u00eda sicol\u00f3gica).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os presento una serie de actividades que organic\u00e9 cuando los alumnos de final de B1 me se\u00f1alaron que les costaba el imperfecto de subjuntivo. 1 &#8211; Repaso de la formaci\u00f3n Si tu manual no lo tiene, podr\u00e1s encontrar un esquema en l\u00ednea. 2a &#8211; Los ejercicios de formaci\u00f3n (lo que<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":24,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[13],"tags":[134],"class_list":["post-25834","post","type-post","status-publish","format-standard","hentry","category-materiales","tag-gramatica"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:57:50","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/25834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=25834"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/25834\/revisions"}],"predecessor-version":[{"id":25839,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/25834\/revisions\/25839"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=25834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=25834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=25834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}