{"id":16165,"date":"2021-05-10T09:57:01","date_gmt":"2021-05-10T09:57:01","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=16165"},"modified":"2021-05-10T09:57:38","modified_gmt":"2021-05-10T09:57:38","slug":"zoom-en-powerpoint","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/zoom-en-powerpoint\/","title":{"rendered":"Zoom en Powerpoint"},"content":{"rendered":"<p>P. Acabo de ver una presentaci\u00f3n en la que hay una diapositiva que hace las veces de \u00edndice y que salta a secciones en la presentaci\u00f3n. Es algo similar a Prezi. \u00bfLo puedo hacer yo tambi\u00e9n?<\/p>\n<p>R. Se llama <em>Zoom<\/em> en Powerpoint, disponible en Office 365. As\u00ed funciona:<\/p>\n<ul>\n<li>creas un \u00edndice (una diapositiva con la lista de las partes)<\/li>\n<li>preparas puntos de anclaje que ser\u00e1n los inicios de las secciones.<br \/>\nInsertar, Zoom, Zoom de resumen<br \/>\nInsertas el \u00edndice y cada uno de los inicios de secci\u00f3n<\/li>\n<\/ul>\n<p>Powerpoint se encarga de crear secciones y todos los tecnicismos necesarios.<\/p>\n<p><em>Usar zoom para PowerPoint para dar vida a la presentaci\u00f3n<\/em> &#8211; Soporte de Office<br \/>\n<a href=\"https:\/\/support.microsoft.com\/es-es\/office\/usar-zoom-para-powerpoint-para-dar-vida-a-la-presentaci%c3%b3n-9d6c58cd-2125-4d29-86b1-0097c7dc47d7?ui=es-ES&#038;rs=es-ES&#038;ad=ES\" class=\"autohyperlink\">support.microsoft.com\/es-es\/office\/usar-zoom-para-powerpoint-para-dar-vida-a-la-presentaci%c3%b3n-9d6c58cd-2125-4d29-86b1-0097c7dc47d7?ui=es-ES&#038;rs=es-ES&#038;ad=ES<\/a><\/p>\n<p>Si no tienes Office 365, puedes construir algo similar con botones y acciones que navegan a las distintas secciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>P. Acabo de ver una presentaci\u00f3n en la que hay una diapositiva que hace las veces de \u00edndice y que salta a secciones en la presentaci\u00f3n. Es algo similar a Prezi. \u00bfLo puedo hacer yo tambi\u00e9n? R. Se llama Zoom en Powerpoint, disponible en Office 365. As\u00ed funciona: creas un<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[32],"tags":[114,101],"class_list":["post-16165","post","type-post","status-publish","format-standard","hentry","category-herramientas","tag-powerpoint","tag-tic"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:00:37","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/16165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=16165"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/16165\/revisions"}],"predecessor-version":[{"id":16166,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/16165\/revisions\/16166"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=16165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=16165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=16165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}