{"id":15977,"date":"2021-04-09T06:12:34","date_gmt":"2021-04-09T06:12:34","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=15977"},"modified":"2025-06-11T10:08:49","modified_gmt":"2025-06-11T10:08:49","slug":"series-en-youtube","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/series-en-youtube\/","title":{"rendered":"Series en Youtube"},"content":{"rendered":"<p>Una lista muy personal de series que se emiten en Youtube y que a veces aconsejo a alumnos curiosos en funci\u00f3n de sus intereses. Menciono Youtube porque no todo el mundo tiene una suscripci\u00f3n a Netflix, y me limito a series con episodios sueltos porque las telenovelas las mencion\u00e9 <a href=\"https:\/\/hlrnet.com\/sites\/alt164\/telenovelas-2\/\">en otra contribuci\u00f3n<\/a>.<\/p>\n<p>Indicaci\u00f3n de tema: [CF] crimen, ficci\u00f3n [CD] crimen, documental [AS] Amor y\/o sociedad<\/p>\n<p>Versi\u00f3n original en castellano<\/p>\n<ul>\n<li>Decisiones [AS]<\/li>\n<li>Decisiones extremas [AS]<\/li>\n<li>El caso [CF]<\/li>\n<li>Lo que callamos las mujeres [AS]<\/li>\n<li>Tu voz est\u00e9reo [AS]<\/li>\n<\/ul>\n<p>Traducido desde el ingl\u00e9s<\/p>\n<ul>\n<li>Cr\u00edmenes imperfectos [CD]<\/li>\n<\/ul>\n<p>Traducido desde el italiano<\/p>\n<ul>\n<li>Alta infidelidad [AS]<\/li>\n<\/ul>\n<p>Traducido desde el alem\u00e1n<\/p>\n<ul>\n<li>Rex, un polic\u00eda especial [CF]<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Una lista muy personal de series que se emiten en Youtube y que a veces aconsejo a alumnos curiosos en funci\u00f3n de sus intereses. Menciono Youtube porque no todo el mundo tiene una suscripci\u00f3n a Netflix, y me limito a series con episodios sueltos porque las telenovelas las mencion\u00e9 en<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":8,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12,13],"tags":[87,202],"class_list":["post-15977","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes","category-materiales","tag-audicion","tag-noticias-y-enlaces"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:59:07","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=15977"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15977\/revisions"}],"predecessor-version":[{"id":26591,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15977\/revisions\/26591"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=15977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=15977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=15977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}