{"id":15191,"date":"2020-09-15T13:18:14","date_gmt":"2020-09-15T13:18:14","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=15191"},"modified":"2024-01-02T13:47:32","modified_gmt":"2024-01-02T13:47:32","slug":"la-miseria-de-las-traducciones","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/la-miseria-de-las-traducciones\/","title":{"rendered":"La miseria de las traducciones"},"content":{"rendered":"<p>De vez en cuando nos hace sobresaltar una traducci\u00f3n rid\u00edcula. Por ejemplo:<\/p>\n<ul>\n<li>El ning\u00fan fumar (4)<\/li>\n<li>En el acontecimiento del fuego no utilice las elevaciones (3)<\/li>\n<li>Esto es un humo \/ un tabaco libera la facilidad (2)<\/li>\n<li>Mano se lava, no blanquear no caiga, hierro chulo (2)<\/li>\n<li>Mantenga pies lejos de entrepa\u00f1o de lado (2)<\/li>\n<li>Ning\u00fan cabalgar descalzo (2)<\/li>\n<li>\u00bfQu\u00e9 se supone que tienes que hacer con esta camiseta? (1)<\/li>\n<li>Sobreto recuerda tener mucho cuidado (1)<\/li>\n<li>Un hombre y dos mujeres cable adaptador de audio (2)<\/li>\n<li>Vuelta lejos chaparrones cuando usted es hecho (2)<\/li>\n<\/ul>\n<p>Fuentes:<\/p>\n<ol>\n<li>Grandes Errores en Traducciones | Planet Lingua<br \/>\n<a href=\"https:\/\/planetlingua.com\/errores-traduccion-desternillantes\/\" class=\"autohyperlink\">planetlingua.com\/errores-traduccion-desternillantes\/<\/a><\/li>\n<li>14 p\u00e9simas traducciones que ni el traductor de Google clava tan bien (mal) | P\u00fablico<br \/>\n<a href=\"https:\/\/www.publico.es\/sociedad\/en-las-redes\/14-pesimas-traducciones-google-translate-clava-mal.html\" class=\"autohyperlink\">www.publico.es\/sociedad\/en-las-redes\/14-pesimas-traducciones-google-translate-clava-mal.html<\/a><\/li>\n<li>The 10 absolute worst English to Spanish translations you will EVER see! (PHOTOS) | <a href=\"http:\/\/MamasLatinas.com\" class=\"autohyperlink\">MamasLatinas.com<\/a><br \/>\n<a href=\"https:\/\/mamaslatinas.com\/news-entertainment\/110948-the_10_absolute_worst_english\" class=\"autohyperlink\">mamaslatinas.com\/news-entertainment\/110948-the_10_absolute_worst_english<\/a><\/li>\n<li>10 Funny Translations From English To Spanish And Vice Versa (SLIDESHOW) | HuffPost<br \/>\n<a href=\"https:\/\/www.huffpost.com\/entry\/10-funny-translations-spanish-english_n_2774588\" class=\"autohyperlink\">www.huffpost.com\/entry\/10-funny-translations-spanish-english_n_2774588<\/a><\/li>\n<\/ol>\n<p>Un campo particular es el del cine, de los t\u00edtulos, y de los nombres de personajes y lugares:<\/p>\n<ol>\n<li>Las (malas) traducciones de Espa\u00f1a y Latinoam\u00e9rica<br \/>\n<a href=\"https:\/\/www.mundopeliculas.tv\/2018\/02\/26\/las-malas-traducciones-espana-latinoamerica\/\" class=\"autohyperlink\">www.mundopeliculas.tv\/2018\/02\/26\/las-malas-traducciones-espana-latinoamerica\/<\/a><\/li>\n<li>Las cinco peores y m\u00e1s rid\u00edculas traducciones de t\u00edtulos de pel\u00edculas | V\u00eda Pa\u00eds<br \/>\n<a href=\"https:\/\/viapais.com.ar\/argentina\/1428812-las-cinco-peores-y-mas-ridiculas-traducciones-de-titulos-de-peliculas\/\" class=\"autohyperlink\">viapais.com.ar\/argentina\/1428812-las-cinco-peores-y-mas-ridiculas-traducciones-de-titulos-de-peliculas\/<\/a><\/li>\n<li>Top 10 Ridiculas Traducciones Del Castellano<br \/>\n<a href=\"https:\/\/ar-cams.com\/video\/FybdXya1Xrc\/top-10-ridiculas-traducciones-del-castellano.html\" class=\"autohyperlink\">ar-cams.com\/video\/FybdXya1Xrc\/top-10-ridiculas-traducciones-del-castellano.html<\/a><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De vez en cuando nos hace sobresaltar una traducci\u00f3n rid\u00edcula. Por ejemplo: El ning\u00fan fumar (4) En el acontecimiento del fuego no utilice las elevaciones (3) Esto es un humo \/ un tabaco libera la facilidad (2) Mano se lava, no blanquear no caiga, hierro chulo (2) Mantenga pies lejos<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[12],"tags":[202],"class_list":["post-15191","post","type-post","status-publish","format-standard","hentry","category-enlaces-interesantes","tag-noticias-y-enlaces"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 18:40:27","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=15191"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15191\/revisions"}],"predecessor-version":[{"id":15192,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/15191\/revisions\/15192"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=15191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=15191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=15191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}