{"id":13691,"date":"2019-09-21T09:15:48","date_gmt":"2019-09-21T09:15:48","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=13691"},"modified":"2023-09-21T17:16:46","modified_gmt":"2023-09-21T17:16:46","slug":"materiales-de-la-jornada-del-21-sept","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/materiales-de-la-jornada-del-21-sept\/","title":{"rendered":"Materiales de la jornada del 21 sept 2019"},"content":{"rendered":"<p><a href=\"http:\/\/aulacorto.mecd.gob.es\/\">Aula corto<\/a><\/p>\n<p><a href=\"http:\/\/eleo.mecd.gob.es\/\">Eleo<\/a><\/p>\n<p>Las stories de instagram<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ECvcJVPX8p\"><p><a href=\"https:\/\/postcron.com\/es\/blog\/instagram-stories\/\">\u201cInstagram Stories\u201d, todo lo que necesitas saber para sacar el m\u00e1ximo provecho de esta funcionalidad<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"&#8220;\u201cInstagram Stories\u201d, todo lo que necesitas saber para sacar el m\u00e1ximo provecho de esta funcionalidad&#8221; &#8212; Blog de Marketing Digital y Social Media - Blog de Postcron\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/postcron.com\/es\/blog\/instagram-stories\/embed\/#?secret=ECvcJVPX8p\" data-secret=\"ECvcJVPX8p\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>El estado de las redes sociales en 2019<\/p>\n<p><a href=\"http:\/\/Jramonele.com\" class=\"autohyperlink\">Jramonele.com<\/a><\/p>\n<p><a href=\"http:\/\/www.jimdo.com\">Jimdo<\/a><\/p>\n<p><a href=\"http:\/\/www.menti.com\">Menti.com<\/a><\/p>\n<p>Canvas para el dise\u00f1o de proyectos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aula corto Eleo Las stories de instagram \u201cInstagram Stories\u201d, todo lo que necesitas saber para sacar el m\u00e1ximo provecho de esta funcionalidad El estado de las redes sociales en 2019 <a href=\"http:\/\/Jramonele.com\" class=\"autohyperlink\">Jramonele.com<\/a> Jimdo <a href=\"http:\/\/Menti.com\" class=\"autohyperlink\">Menti.com<\/a> Canvas para el dise\u00f1o de proyectos<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[13],"tags":[],"class_list":["post-13691","post","type-post","status-publish","format-standard","hentry","category-materiales"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:59:35","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=13691"}],"version-history":[{"count":3,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13691\/revisions"}],"predecessor-version":[{"id":23069,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13691\/revisions\/23069"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=13691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=13691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=13691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}