{"id":13466,"date":"2019-07-15T13:44:03","date_gmt":"2019-07-15T13:44:03","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=13466"},"modified":"2026-02-14T16:15:29","modified_gmt":"2026-02-14T16:15:29","slug":"herramientas-presentadas-en-la-revista-puente","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/herramientas-presentadas-en-la-revista-puente\/","title":{"rendered":"Herramientas presentadas en la revista Puente"},"content":{"rendered":"<p>Unas herramientas que present\u00e9 en la revista PUENTE<\/p>\n<ul>\n<li>Puente 172 (2019)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=4317\">Uso de herramientas TIC en y para la clase de ELE: trampas y pautas<\/a><\/li>\n<li>Puente 169 (2018)<\/li>\n<li><a href=\"https:\/\/sbpe.be\/site\/?page_id=4036\">El aprendizaje por proyectos: puntos de partida<\/a><\/li>\n<li>Puente 166 (2017)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3764\">Redactar ejercicios para uso en clase<\/a><\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3782\">Preparar ejercicios y actividades para el autoestudio<\/a><\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3790\">Jugar a los dados \u2013 sin dados<\/a><\/li>\n<li>Puente 165 (2017)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3568\">Powerpoint Mix, Onenote y Sway: tres olvidados de Office<\/a><\/li>\n<li>Puente 164 (2017)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3494\">C\u00f3mo seleccionar documentos aut\u00e9nticos<\/a><\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3479\">La selecci\u00f3n m\u00faltiple: m\u00e1s all\u00e1 de la correcci\u00f3n de pruebas<\/a><\/li>\n<li>Puente 162 (2016)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3231\">Cervantes 400 a\u00f1os despu\u00e9s: el Quijote y la web<\/a><\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3248\">Trampas de las TIC explicadas a esc\u00e9pticos ingenuos<\/a><\/li>\n<li>Puente 160 (2016)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=3025\">B\u00fasquedas din\u00e1micas al servicio del estudio y la ense\u00f1anza de la lengua<\/a><\/li>\n<li>Puente 159 (2015)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=2877\">Subt\u00edtulos y YouTube<\/a><\/li>\n<li>Puente 155 (2013)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=2271\">Glosbe: traducci\u00f3n participativa y contextualizada<\/a><\/li>\n<li>Puente 153 (2013)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=2144\">Microdocumentos<\/a><\/li>\n<li>Puente 136 (2009)<\/li>\n<li><a href=\"http:\/\/sbpe.be\/site\/?page_id=863\">Sitios con cursos en l\u00ednea<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unas herramientas que present\u00e9 en la revista PUENTE Puente 172 (2019) Uso de herramientas TIC en y para la clase de ELE: trampas y pautas Puente 169 (2018) El aprendizaje por proyectos: puntos de partida Puente 166 (2017) Redactar ejercicios para uso en clase Preparar ejercicios y actividades para el<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[32],"tags":[],"class_list":["post-13466","post","type-post","status-publish","format-standard","hentry","category-herramientas"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:59:22","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=13466"}],"version-history":[{"count":3,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13466\/revisions"}],"predecessor-version":[{"id":27363,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/13466\/revisions\/27363"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=13466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=13466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=13466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}