{"id":12718,"date":"2018-10-25T10:44:32","date_gmt":"2018-10-25T10:44:32","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=12718"},"modified":"2018-10-25T10:44:32","modified_gmt":"2018-10-25T10:44:32","slug":"construir-conversaciones-y-debates","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/construir-conversaciones-y-debates\/","title":{"rendered":"Construir conversaciones y debates"},"content":{"rendered":"<p>Unas ideas para construir conversaciones y debates:<\/p>\n<ul>\n<li>A partir un <strong>tema<\/strong> (tratado en los materiales) y\/o un <strong>texto<\/strong> aut\u00e9ntico (eventualmente en parte [el t\u00edtulo, por ejemplo] o adaptado)<\/li>\n<li>se formulan una serie de tesis \/ <strong>afirmaciones<\/strong> que pueden ser matizadas o extremas<\/li>\n<li>los alumnos reaccionan a dichas afirmaciones expresando su acuerdo o desacuerdo, formulando <strong>argumentos<\/strong><\/li>\n<li>eventualmente a partir de un <strong>papel<\/strong> que desempe\u00f1an (un papelito con la descripci\u00f3n de un personaje en un contexto, o un papel que dice si tienen que estar a favor o en contra, como un abogado)<\/li>\n<\/ul>\n<p>Adem\u00e1s se puede trabajar a partir de <strong>informaciones<\/strong><\/p>\n<ul>\n<li>Cada uno de los alumnos dispone de una parte de la informaci\u00f3n\n<ul>\n<li>por ejemplo, algo que los otros no pueden saber (la familia o la casa de uno, por ejemplo, o algo contenido en un documento)<\/li>\n<\/ul>\n<\/li>\n<li>Y en grupos de 2, 3 \u00f3 4 reconstituyen o intercambian la informaci\u00f3n\n<ul>\n<li>buscar puntos comunes<\/li>\n<li>reconstituir una tabla, un esquema, &#8230;<\/li>\n<\/ul>\n<\/li>\n<li>Despu\u00e9s de lo cual se verifica<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Unas ideas para construir conversaciones y debates: A partir un tema (tratado en los materiales) y\/o un texto aut\u00e9ntico (eventualmente en parte [el t\u00edtulo, por ejemplo] o adaptado) se formulan una serie de tesis \/ afirmaciones que pueden ser matizadas o extremas los alumnos reaccionan a dichas afirmaciones expresando su<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[32,13],"tags":[106],"class_list":["post-12718","post","type-post","status-publish","format-standard","hentry","category-herramientas","category-materiales","tag-conversacion"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 16:59:36","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=12718"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12718\/revisions"}],"predecessor-version":[{"id":12970,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12718\/revisions\/12970"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=12718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=12718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=12718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}