{"id":1240,"date":"2012-06-20T21:02:35","date_gmt":"2012-06-20T21:02:35","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=1240"},"modified":"2016-06-13T11:30:29","modified_gmt":"2016-06-13T11:30:29","slug":"mendoza-y-su-detective-loco","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/mendoza-y-su-detective-loco\/","title":{"rendered":"Mendoza y su detective loco"},"content":{"rendered":"<p>Una pista para los lectores de mendoza que han apreciado (como yo &#8211; soy un fan incondicional) <em>El misterio de la cripta embrujada<\/em> y <em>El laberinto de las aceitunas<\/em>: el detective loco est\u00e1 de vuelta en El enredo de la bolsa y la vida, publicado en 2011. Y hay un dossier muy interesante en <a href=\"http:\/\/dossier.elenredodelabolsaylavida.com\/\">dossier.elenredodelabolsaylavida.com\/<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una pista para los lectores de mendoza que han apreciado (como yo &#8211; soy un fan incondicional) El misterio de la cripta embrujada y El laberinto de las aceitunas: el detective loco est\u00e1 de vuelta en El enredo de la bolsa y la vida, publicado en 2011. Y hay un<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[29],"tags":[98],"class_list":["post-1240","post","type-post","status-publish","format-standard","hentry","category-literatura","tag-literatura"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:40:57","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/1240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=1240"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/1240\/revisions"}],"predecessor-version":[{"id":9418,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/1240\/revisions\/9418"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=1240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=1240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=1240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}