{"id":12353,"date":"2018-07-24T14:00:28","date_gmt":"2018-07-24T14:00:28","guid":{"rendered":"https:\/\/hlrnet.com\/sites\/alt164\/?p=12353"},"modified":"2018-07-24T14:00:28","modified_gmt":"2018-07-24T14:00:28","slug":"ngram-para-interrogar-ocurrencias-en-google-books","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/ngram-para-interrogar-ocurrencias-en-google-books\/","title":{"rendered":"Ngram para interrogar ocurrencias en Google Books"},"content":{"rendered":"<p>Google Ngram es una aplicaci\u00f3n en l\u00ednea que muestra la frecuencia relativa de t\u00e9rminos de b\u00fasqueda en una parte (un territorio ling\u00fc\u00edstico, una lengua) de Google Books.<\/p>\n<p>Por ejemplo:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12355 alignnone\" src=\"https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom-300x167.png\" alt=\"\" width=\"300\" height=\"167\" srcset=\"https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom-300x167.png 300w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom-768x428.png 768w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom-360x200.png 360w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom-450x250.png 450w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-enscom.png 907w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><em>ense\u00f1anza comunicativa<\/em> (que, como se pude ver, ya estuvo de moda antes)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12356 alignnone\" src=\"https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-ele-300x192.png\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-ele-300x192.png 300w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-ele-768x491.png 768w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2018\/07\/ngram-ele.png 906w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><em>espa\u00f1ol lengua extranjera<\/em><\/p>\n<p>As\u00ed funciona:<\/p>\n<ul>\n<li>defines el t\u00e9rmino de b\u00fasqueda (o los distintos t\u00e9rminos que quieres comparar)<\/li>\n<li>decides del periodo dentro del cual quieres buscar<\/li>\n<\/ul>\n<p>M\u00e1s explicaciones en <a href=\"https:\/\/books.google.com\/ngrams\/info\">esta ficha de ayuda<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google Ngram es una aplicaci\u00f3n en l\u00ednea que muestra la frecuencia relativa de t\u00e9rminos de b\u00fasqueda en una parte (un territorio ling\u00fc\u00edstico, una lengua) de Google Books. Por ejemplo: ense\u00f1anza comunicativa (que, como se pude ver, ya estuvo de moda antes) espa\u00f1ol lengua extranjera As\u00ed funciona: defines el t\u00e9rmino de<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[32],"tags":[160],"class_list":["post-12353","post","type-post","status-publish","format-standard","hentry","category-herramientas","tag-corpus"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 18:00:22","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=12353"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12353\/revisions"}],"predecessor-version":[{"id":12357,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/12353\/revisions\/12357"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=12353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=12353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=12353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}