{"id":10890,"date":"2017-09-14T19:59:10","date_gmt":"2017-09-14T19:59:10","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=10890"},"modified":"2026-02-02T19:20:12","modified_gmt":"2026-02-02T19:20:12","slug":"mano-foto-radio-moto-modelo","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/mano-foto-radio-moto-modelo\/","title":{"rendered":"mano foto radio moto + modelo"},"content":{"rendered":"<p>Cuatro palabras femeninas que terminan en -o, y una que puede ser femenina. \u00bfPor qu\u00e9?<\/p>\n<ul>\n<li>la mano, la radio, la foto , el\/la modelo<\/li>\n<li>las abreviaciones de palabras radiograf\u00eda, fotograf\u00eda<\/li>\n<li>por razones de etimolog\u00eda<\/li>\n<li>y &#8211; m\u00e1s sencillamente &#8211; porque es una mentira grosera asociar -o con el masculino y -a con femenino; es inducir a los aprendices (belga<strong>s, <\/strong>optimist<strong>a<\/strong>s y pesimist<strong>a<\/strong>s) en error, y por lo tanto un error profesional, eso lo ve cualquier<strong>a<\/strong>.<\/li>\n<li>adem\u00e1s, no olvides adem\u00e1s de el\/la modelo: el\/la testigo, el\/la piloto.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro palabras femeninas que terminan en -o, y una que puede ser femenina. \u00bfPor qu\u00e9? la mano, la radio, la foto , el\/la modelo las abreviaciones de palabras radiograf\u00eda, fotograf\u00eda por razones de etimolog\u00eda y &#8211; m\u00e1s sencillamente &#8211; porque es una mentira grosera asociar -o con el masculino y<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":16,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1],"tags":[],"class_list":["post-10890","post","type-post","status-publish","format-standard","hentry","category-noticias"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:41:08","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=10890"}],"version-history":[{"count":2,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10890\/revisions"}],"predecessor-version":[{"id":27299,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10890\/revisions\/27299"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=10890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=10890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=10890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}