{"id":10702,"date":"2017-07-05T13:42:37","date_gmt":"2017-07-05T13:42:37","guid":{"rendered":"http:\/\/hlrnet.com\/sites\/alt164\/?p=10702"},"modified":"2020-03-20T11:13:10","modified_gmt":"2020-03-20T11:13:10","slug":"symbaloo-presentar-coleccion-de-enlaces","status":"publish","type":"post","link":"https:\/\/hlrnet.com\/sites\/alt164\/symbaloo-presentar-coleccion-de-enlaces\/","title":{"rendered":"Symbaloo: presentar colecci\u00f3n de enlaces"},"content":{"rendered":"<p><a href=\"http:\/\/www.symbaloo.com\/\">Symbaloo<\/a> es una web que permite confeccionar colecciones de enlaces que luego se pueden comunicar al p\u00fablico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-10703\" src=\"http:\/\/hlrnet.com\/sites\/alt164\/files\/2017\/07\/symbaloo-300x120.png\" alt=\"\" width=\"300\" height=\"120\" srcset=\"https:\/\/hlrnet.com\/sites\/alt164\/files\/2017\/07\/symbaloo-300x120.png 300w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2017\/07\/symbaloo-768x308.png 768w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2017\/07\/symbaloo-1024x411.png 1024w, https:\/\/hlrnet.com\/sites\/alt164\/files\/2017\/07\/symbaloo.png 1747w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Estas son las etapas:<\/p>\n<ol>\n<li>Entrar a la web<\/li>\n<li>Crear una colecci\u00f3n<\/li>\n<li>Poblarla<\/li>\n<li>Comunicar su direcci\u00f3n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Symbaloo es una web que permite confeccionar colecciones de enlaces que luego se pueden comunicar al p\u00fablico. Estas son las etapas: Entrar a la web Crear una colecci\u00f3n Poblarla Comunicar su direcci\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":5,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[32],"tags":[170,168,101],"class_list":["post-10702","post","type-post","status-publish","format-standard","hentry","category-herramientas","tag-a-distancia","tag-enlaces","tag-tic"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:40:58","action":"delete","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/comments?post=10702"}],"version-history":[{"count":1,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10702\/revisions"}],"predecessor-version":[{"id":10704,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/posts\/10702\/revisions\/10704"}],"wp:attachment":[{"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/media?parent=10702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/categories?post=10702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hlrnet.com\/sites\/alt164\/wp-json\/wp\/v2\/tags?post=10702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}